{"id":27242,"date":"2022-08-04T16:39:05","date_gmt":"2022-08-04T20:39:05","guid":{"rendered":"https:\/\/www.affiliated1031.com\/form-worksheet\/"},"modified":"2023-04-26T17:38:44","modified_gmt":"2023-04-26T21:38:44","slug":"hoja-de-trabajo-del-cliente","status":"publish","type":"page","link":"https:\/\/www.affiliated1031.com\/es\/hoja-de-trabajo-del-cliente\/","title":{"rendered":"Hoja de trabajo del cliente"},"content":{"rendered":"<div  class=\"tatsu-BynL4I_Yac tatsu-section  tatsu-bg-overlay   tatsu-clearfix\" data-title=\"\"  data-headerscheme=\"background--dark\"><div class='tatsu-section-pad clearfix' data-padding='{\"d\":\"0px 0px 0px 0px\"}' data-padding-top='0px'><div class=\"tatsu-row-wrap  tatsu-row-full-width tatsu-row-one-col tatsu-row-has-one-cols tatsu-medium-gutter tatsu-reg-cols  tatsu-clearfix tatsu-SJoLNLOYa9\" ><div  class=\"tatsu-row \" ><div  class=\"tatsu-column  tatsu-bg-overlay tatsu-one-col tatsu-column-image-none tatsu-column-effect-none  tatsu-By98VL_FTc\"  data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" >            <div class = \"tatsu-rev-slider-wrap tatsu-module  tatsu-Hy9erLOKp5\">\n                \n\t\t\t<!-- START ESP Client worksheet REVOLUTION SLIDER 6.5.18 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_38_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:#ffffff;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_38_1\" style=\"\" data-version=\"6.5.18\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-44\" data-title=\"Slide\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/\/www.affiliated1031.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"banner-2\" width=\"1920\" height=\"776\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.affiliated1031.com\/wp-content\/uploads\/2022\/08\/banner-2-3.png\" data-bg=\"p:center bottom;\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-group\n\t\t\t\t\t\t\t\tid=\"slider-38-slide-44-layer-3\" \n\t\t\t\t\t\t\t\tdata-type=\"group\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,1px;yo:595px,442px,361px,393px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,12,8,4;l:0,15,10,6;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:1201px,725px,622px,383px;h:180px,108px,72px,86px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"o:1;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sA:9000;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;\"\n\t\t\t\t\t\t\t><!--\n\t\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\t\tid=\"slider-38-slide-44-layer-5\" \n\t\t\t\t\t\t\t\t\tclass=\"rev-btn\"\n\t\t\t\t\t\t\t\t\tdata-type=\"button\"\n\t\t\t\t\t\t\t\t\tdata-bsh=\"c:rgba(0,0,0,0.25);v:10px,6px,4px,2px;b:10px,6px,4px,2px;\"\n\t\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\t\tdata-xy=\"x:c;yo:50px,30px,20px,12px;\"\n\t\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:35,21,14,25;l:50,30,20,15;fw:500;a:center;\"\n\t\t\t\t\t\t\t\t\tdata-dim=\"w:600px,362px,300px,350px;minh:0px,none,none,none;\"\n\t\t\t\t\t\t\t\t\tdata-margin=\"r:0,0,0,15;l:0,0,0,15;\"\n\t\t\t\t\t\t\t\t\tdata-padding=\"t:15,9,6,25;b:15,9,6,25;\"\n\t\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\t\tdata-frame_hover=\"bgc:#20295c;bor:0px,0px,0px,0px;bri:120%;\"\n\t\t\t\t\t\t\t\t\tstyle=\"z-index:11;background-color:#1b96d3;font-family:'Roboto';\"\n\t\t\t\t\t\t\t\t>Comience Su 1031 Ahora \n\t\t\t\t\t\t\t\t<\/rs-layer><!--\n\t\t\t\t\t\t\t--><\/rs-group><!--\n\n\t\t\t\t\t\t\t--><h1\n\t\t\t\t\t\t\t\tid=\"slider-38-slide-44-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:t,m,t,t;yo:246px,-32px,150px,108px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:90,55,55,45;l:90,65,55,45;fw:700;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:1285px,1063px,728px,448px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:45px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:300;sp:700;sR:300;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"y:45px;o:0;st:w;sp:700;sR:8000;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Roboto';\"\n\t\t\t\t\t\t\t>Hoja de trabajo del cliente  \n\t\t\t\t\t\t\t<\/h1><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_38_1',rl:[1240,1024,778,480],el:[930,600,600,600],gw:[1920,1160,778,480],gh:[930,600,600,600],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider381\"]!==undefined) {window.RS_MODULES.modules[\"revslider381\"].once = false;window.revapi38 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n            <\/div>\n<\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image tatsu-bg-lazyload\" data-src = \"\"><\/div><\/div><div class=\"tatsu-overlay tatsu-column-overlay tatsu-animate-none\" ><\/div><\/div><style>.tatsu-row > .tatsu-By98VL_FTc.tatsu-column{width: 100%;}.tatsu-By98VL_FTc.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: normal;}.tatsu-By98VL_FTc > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-By98VL_FTc > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-By98VL_FTc > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-By98VL_FTc > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}@media only screen and (max-width:1377px) {.tatsu-row > .tatsu-By98VL_FTc.tatsu-column{width: 100%;}}@media only screen and (min-width:768px) and (max-width: 1024px) {.tatsu-row > .tatsu-By98VL_FTc.tatsu-column{width: 100%;}}@media only screen and (max-width: 767px) {.tatsu-row > .tatsu-By98VL_FTc.tatsu-column{width: 100%;}}<\/style><\/div><\/div><\/div><\/div><div class=\"tatsu-section-background-wrap\"><div class = \"tatsu-section-background tatsu-bg-lazyload\" data-src = \"\"><\/div><\/div><div class=\"tatsu-overlay tatsu-section-overlay\"><\/div><style>.tatsu-BynL4I_Yac .tatsu-section-offset-wrap{transform: translateY(-0px);}.tatsu-BynL4I_Yac > .tatsu-bottom-divider{z-index: 9999;}.tatsu-BynL4I_Yac > .tatsu-top-divider{z-index: 9999;}.tatsu-BynL4I_Yac .tatsu-section-overlay{mix-blend-mode: normal;}<\/style><\/div><div  class=\"tatsu-ByW3LUOKa5 tatsu-section  tatsu-bg-overlay   tatsu-clearfix\" data-title=\"\"  data-headerscheme=\"background--dark\"><div class='tatsu-section-pad clearfix' data-padding='{\"d\":\"90px 0px 90px 0px\",\"m\":\"40px 0px 60px 0px\"}' data-padding-top='40px'><div class=\"tatsu-row-wrap  tatsu-wrap tatsu-row-one-col tatsu-row-has-one-cols tatsu-medium-gutter tatsu-reg-cols  tatsu-clearfix tatsu-rJx388dYa9\" ><style>@media only screen and (max-width: 767px) {.tatsu-rJx388dYa9.tatsu-row-wrap > .tatsu-row{padding: 0px 0px 0px 0px;}}<\/style><div  class=\"tatsu-row \" ><div  class=\"tatsu-column  tatsu-bg-overlay tatsu-one-col tatsu-column-image-none tatsu-column-effect-none  tatsu-rJnILdFT9\"  data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" >        <div  class = \"tatsu-wp-forms tatsu-module  tatsu-SJQPLuta9 \" >\n            <style>.tatsu-SJQPLuta9{border-width: 0px 0px 0px 0px;border-style: solid;}@media only screen and (max-width: 767px) {.tatsu-SJQPLuta9{padding: 0px 0 0 0;margin: 0px 0 0 0;}}<\/style>            <div class = \"tatsu-wp-forms-inner tatsu-wp-form-rounded tatsu-wp-form-submit-rounded\">\n                <div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-27245\"><form id=\"wpforms-form-27245\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"27245\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/27242\" data-token=\"5e8b052284b5dfffbc84edc72ca8947e\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-27245-field_55-container\" class=\"wpforms-field wpforms-field-text title\" data-field-id=\"55\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-27245-field_55\">Single Line Text<\/label><input type=\"text\" id=\"wpforms-27245-field_55\" class=\"wpforms-field-medium\" name=\"wpforms[fields][55]\" ><div class=\"wpforms-field-description\"><p><span class=\"verdecito\">Empiece ahora mismo. <\/span>Complete el formulario y podr\u00e1 comenzar a diferir los impuestos sobre las ganancias de capital y preservar su patrimonio.<\/p><\/div><\/div><div id=\"wpforms-27245-field_18-container\" class=\"wpforms-field wpforms-field-text title\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_18\">INFORMACI\u00d3N DEL CAMBISTA<\/label><input type=\"text\" id=\"wpforms-27245-field_18\" class=\"wpforms-field-large\" name=\"wpforms[fields][18]\" ><\/div><div id=\"wpforms-27245-field_6-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_6\">Su nombre <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_6\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][6]\" required><\/div><div id=\"wpforms-27245-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_7\">Direcci\u00f3n <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-27245-field_7\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][7]\" required><\/textarea><\/div><div id=\"wpforms-27245-field_5-container\" class=\"wpforms-field wpforms-field-text wpforms-two-fourths wpforms-first wpforms-full\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_5\">Ciudad <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_5\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-27245-field_8-container\" class=\"wpforms-field wpforms-field-text wpforms-one-fourth wpforms-full\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_8\">Estado <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_8\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][8]\" required><\/div><div id=\"wpforms-27245-field_9-container\" class=\"wpforms-field wpforms-field-text wpforms-one-fourth wpforms-full\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_9\">C\u00f3digo postal <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_9\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][9]\" required><\/div><div id=\"wpforms-27245-field_11-container\" class=\"wpforms-field wpforms-field-text wpforms-two-thirds wpforms-first wpforms-full\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_11\">Tel\u00e9fono del trabajo <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_11\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][11]\" required><\/div><div id=\"wpforms-27245-field_12-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-full\" data-field-id=\"12\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_12\">Tel\u00e9fono fijo <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_12\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][12]\" required><\/div><div id=\"wpforms-27245-field_13-container\" class=\"wpforms-field wpforms-field-text wpforms-two-thirds wpforms-first wpforms-full\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_13\">Correo electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_13\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][13]\" required><\/div><div id=\"wpforms-27245-field_14-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-full\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_14\">N\u00famero de fax<\/label><input type=\"text\" id=\"wpforms-27245-field_14\" class=\"wpforms-field-large\" name=\"wpforms[fields][14]\" ><\/div><div id=\"wpforms-27245-field_15-container\" class=\"wpforms-field wpforms-field-text wpforms-two-thirds wpforms-first wpforms-full\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_15\">SSN\/TIN<\/label><input type=\"text\" id=\"wpforms-27245-field_15\" class=\"wpforms-field-large\" name=\"wpforms[fields][15]\" ><\/div><div id=\"wpforms-27245-field_16-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-full\" data-field-id=\"16\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_16\">N.\u00b0 de SSN\/N.\u00b0 de TIN adicionales<\/label><input type=\"text\" id=\"wpforms-27245-field_16\" class=\"wpforms-field-large\" name=\"wpforms[fields][16]\" ><\/div><div id=\"wpforms-27245-field_17-container\" class=\"wpforms-field wpforms-field-text title\" data-field-id=\"17\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_17\">PROPIEDAD DE INTERCAMBIO<\/label><input type=\"text\" id=\"wpforms-27245-field_17\" class=\"wpforms-field-large\" name=\"wpforms[fields][17]\" ><\/div><div id=\"wpforms-27245-field_19-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"19\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_19\">Propietario del t\u00edtulo de propiedad  <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_19\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][19]\" required><\/div><div id=\"wpforms-27245-field_20-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"20\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_20\">Direcci\u00f3n <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-27245-field_20\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][20]\" required><\/textarea><\/div><div id=\"wpforms-27245-field_52-container\" class=\"wpforms-field wpforms-field-text wpforms-two-fourths wpforms-first wpforms-full\" data-field-id=\"52\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_52\">Ciudad <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_52\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][52]\" required><\/div><div id=\"wpforms-27245-field_53-container\" class=\"wpforms-field wpforms-field-text wpforms-one-fourth wpforms-full\" data-field-id=\"53\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_53\">Estado <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_53\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][53]\" required><\/div><div id=\"wpforms-27245-field_54-container\" class=\"wpforms-field wpforms-field-text wpforms-one-fourth wpforms-full\" data-field-id=\"54\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_54\">C\u00f3digo postal <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_54\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][54]\" required><\/div><div id=\"wpforms-27245-field_22-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"22\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_22\">Nombre del comprador <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_22\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][22]\" required><\/div><div id=\"wpforms-27245-field_23-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"23\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_23\">Precio de venta <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-27245-field_23\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][23]\" required><\/div><div id=\"wpforms-27245-field_49-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"49\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_49\">Tipo de propiedad: <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_49\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_49_1\" name=\"wpforms[fields][49][]\" value=\"Casa\/condominio de inversi\u00f3n\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_49_1\">Casa\/condominio de inversi\u00f3n<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_49_2\" name=\"wpforms[fields][49][]\" value=\"Comercial\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_49_2\">Comercial<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_49_3\" name=\"wpforms[fields][49][]\" value=\"Industria\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_49_3\">Industria<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_49_4\" name=\"wpforms[fields][49][]\" value=\"Hosteler\u00eda\/restauraci\u00f3n\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_49_4\">Hosteler\u00eda\/restauraci\u00f3n<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_49_5\" name=\"wpforms[fields][49][]\" value=\"Oficinas\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_49_5\">Oficinas<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_49_6\" name=\"wpforms[fields][49][]\" value=\"Plurifamiliar\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_49_6\">Plurifamiliar<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_49_7\" name=\"wpforms[fields][49][]\" value=\"Sin procesar\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_49_7\">Sin procesar<\/label><\/li><li class=\"choice-8 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_49_8\" name=\"wpforms[fields][49][]\" value=\"Venta de terrenos\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_49_8\">Venta de terrenos<\/label><\/li><li class=\"choice-9 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_49_9\" name=\"wpforms[fields][49][]\" value=\"Personal\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_49_9\">Personal<\/label><\/li><li class=\"choice-10 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_49_10\" name=\"wpforms[fields][49][]\" value=\"Otro\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_49_10\">Otro<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_25-container\" class=\"wpforms-field wpforms-field-text title\" data-field-id=\"25\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_25\">AGENTE DE LIQUIDACI\u00d3N\/FIDEICOMISO<\/label><input type=\"text\" id=\"wpforms-27245-field_25\" class=\"wpforms-field-large\" name=\"wpforms[fields][25]\" ><\/div><div id=\"wpforms-27245-field_26-container\" class=\"wpforms-field wpforms-field-text wpforms-two-thirds wpforms-first wpforms-full\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_26\">Nombre del agente<\/label><input type=\"text\" id=\"wpforms-27245-field_26\" class=\"wpforms-field-large\" name=\"wpforms[fields][26]\" ><\/div><div id=\"wpforms-27245-field_27-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-full\" data-field-id=\"27\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_27\">Tel\u00e9fono<\/label><input type=\"text\" id=\"wpforms-27245-field_27\" class=\"wpforms-field-large\" name=\"wpforms[fields][27]\" ><\/div><div id=\"wpforms-27245-field_28-container\" class=\"wpforms-field wpforms-field-text wpforms-two-thirds wpforms-first wpforms-full\" data-field-id=\"28\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_28\">N\u00famero de expediente<\/label><input type=\"text\" id=\"wpforms-27245-field_28\" class=\"wpforms-field-large\" name=\"wpforms[fields][28]\" ><\/div><div id=\"wpforms-27245-field_29-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-full\" data-field-id=\"29\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_29\">Comentarios<\/label><input type=\"text\" id=\"wpforms-27245-field_29\" class=\"wpforms-field-large\" name=\"wpforms[fields][29]\" ><\/div><div id=\"wpforms-27245-field_30-container\" class=\"wpforms-field wpforms-field-text title\" data-field-id=\"30\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_30\">PREGUNTAS ADICIONALES<\/label><input type=\"text\" id=\"wpforms-27245-field_30\" class=\"wpforms-field-large\" name=\"wpforms[fields][30]\" ><\/div><div id=\"wpforms-27245-field_31-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-first wpforms-full label-ajustada wpforms-list-inline\" data-field-id=\"31\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_31\">\u00bfHabl\u00f3 con un representante? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_31\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_31_1\" name=\"wpforms[fields][31][]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_31_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_31_2\" name=\"wpforms[fields][31][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_31_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_32-container\" class=\"wpforms-field wpforms-field-text wpforms-two-thirds wpforms-full\" data-field-id=\"32\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_32\">Nombre del agente (si lo conoce)<\/label><input type=\"text\" id=\"wpforms-27245-field_32\" class=\"wpforms-field-large\" name=\"wpforms[fields][32]\" ><\/div><div id=\"wpforms-27245-field_33-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-one-third wpforms-first wpforms-full wpforms-list-inline\" data-field-id=\"33\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_33\">\u00bfEst\u00e1 listo para hacer un intercambio pronto? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_33\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_33_1\" name=\"wpforms[fields][33][]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_33_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_33_2\" name=\"wpforms[fields][33][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_33_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_34-container\" class=\"wpforms-field wpforms-field-text wpforms-two-thirds wpforms-full\" data-field-id=\"34\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_34\">\u00bfCu\u00e1ndo va a vender su propiedad?<\/label><input type=\"text\" id=\"wpforms-27245-field_34\" class=\"wpforms-field-large\" name=\"wpforms[fields][34]\" ><\/div><div id=\"wpforms-27245-field_35-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"35\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_35\">\u00bfTiene una propiedad de reemplazo en mente?  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_35\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_35_1\" name=\"wpforms[fields][35][]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_35_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_35_2\" name=\"wpforms[fields][35][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_35_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_37-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"37\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_37\">\u00bfCu\u00e1ndo planea comprar una propiedad de reemplazo?  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_37\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_37_1\" name=\"wpforms[fields][37][]\" value=\"Inmediatamente \" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_37_1\">Inmediatamente <\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_37_2\" name=\"wpforms[fields][37][]\" value=\"1 mes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_37_2\">1 mes<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_37_4\" name=\"wpforms[fields][37][]\" value=\"2 - 3 meses\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_37_4\">2 - 3 meses<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_37_5\" name=\"wpforms[fields][37][]\" value=\"3 - 6 meses\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_37_5\">3 - 6 meses<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_37_6\" name=\"wpforms[fields][37][]\" value=\"N\/A\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_37_6\">N\/A<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_38-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"38\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_38\">\u00bfEs la propiedad que vende su casa?  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_38\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_38_1\" name=\"wpforms[fields][38][]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_38_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_38_2\" name=\"wpforms[fields][38][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_38_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_39-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"39\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_39\">\u00bfProporcionar\u00e1 financiamiento al vendedor en la venta de su propiedad? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_39\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_39_1\" name=\"wpforms[fields][39][]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_39_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_39_2\" name=\"wpforms[fields][39][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_39_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_40-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"40\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_40\">\u00bfEs el vendedor\/cambista una entidad extranjera o extranjera no residente? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_40\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_40_1\" name=\"wpforms[fields][40][]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_40_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_40_2\" name=\"wpforms[fields][40][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_40_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_41-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"41\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_41\">\u00bfLa propiedad se mantuvo para inversi\u00f3n o uso productivo en un comercio o empresa?  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_41\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_41_1\" name=\"wpforms[fields][41][]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_41_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_41_2\" name=\"wpforms[fields][41][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_41_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_42-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"42\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_42\">\u00bfEl comprador del inmueble est\u00e1 relacionado con el vendedor\/cambista? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_42\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_42_1\" name=\"wpforms[fields][42][]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_42_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_42_2\" name=\"wpforms[fields][42][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_42_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_43-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"43\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_43\">\u00bfIncluye la propiedad alg\u00fan art\u00edculo significativo que no se incluya tradicionalmente en la venta o bienes ra\u00edces?  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_43\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_43_1\" name=\"wpforms[fields][43][]\" value=\"Si\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_43_1\">Si<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_43_2\" name=\"wpforms[fields][43][]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_43_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_44-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-inline\" data-field-id=\"44\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_44\">\u00bfD\u00f3nde oy\u00f3 hablar de nosotros?  <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-27245-field_44\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_44_1\" name=\"wpforms[fields][44][]\" value=\"Publicidad por correo\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_44_1\">Publicidad por correo<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_44_2\" name=\"wpforms[fields][44][]\" value=\"Recomendaci\u00f3n profesional\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_44_2\">Recomendaci\u00f3n profesional<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_44_3\" name=\"wpforms[fields][44][]\" value=\"Internet\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_44_3\">Internet<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_44_4\" name=\"wpforms[fields][44][]\" value=\"Ferias comerciales\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_44_4\">Ferias comerciales<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_44_5\" name=\"wpforms[fields][44][]\" value=\"Filiales \" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_44_5\">Filiales <\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_44_6\" name=\"wpforms[fields][44][]\" value=\"De un amigo\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_44_6\">De un amigo<\/label><\/li><li class=\"choice-7 depth-1\"><input type=\"checkbox\" id=\"wpforms-27245-field_44_7\" name=\"wpforms[fields][44][]\" value=\"Otro\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-27245-field_44_7\">Otro<\/label><\/li><\/ul><\/div><div id=\"wpforms-27245-field_45-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"45\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_45\">C\u00f3digo promocional (si corresponde):<\/label><input type=\"text\" id=\"wpforms-27245-field_45\" class=\"wpforms-field-large\" name=\"wpforms[fields][45]\" ><\/div><div id=\"wpforms-27245-field_46-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-first wpforms-full\" data-field-id=\"46\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_46\">Remitido por:<\/label><input type=\"text\" id=\"wpforms-27245-field_46\" class=\"wpforms-field-large\" name=\"wpforms[fields][46]\" ><\/div><div id=\"wpforms-27245-field_47-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-full\" data-field-id=\"47\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_47\">Tel\u00e9fono del remitente:<\/label><input type=\"text\" id=\"wpforms-27245-field_47\" class=\"wpforms-field-large\" name=\"wpforms[fields][47]\" ><\/div><div id=\"wpforms-27245-field_48-container\" class=\"wpforms-field wpforms-field-text wpforms-one-third wpforms-full\" data-field-id=\"48\"><label class=\"wpforms-field-label\" for=\"wpforms-27245-field_48\">N.\u00b0 de identificaci\u00f3n de Desarrolladores de empresas del remitente (si corresponde):<\/label><input type=\"text\" id=\"wpforms-27245-field_48\" class=\"wpforms-field-large\" name=\"wpforms[fields][48]\" ><\/div><div id=\"wpforms-27245-field_50-container\" class=\"wpforms-field wpforms-field-text title\" data-field-id=\"50\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-27245-field_50\">Single Line Text<\/label><input type=\"text\" id=\"wpforms-27245-field_50\" class=\"wpforms-field-large\" name=\"wpforms[fields][50]\" ><div class=\"wpforms-field-description\">Al completar este formulario no se est\u00e1 obligando a s\u00ed mismo. Si tiene alguna pregunta o requisito especial, comun\u00edquese con nosotros al 1 (877) USE-1031 o por correo electr\u00f3nico a info@affiliated1031.com.\r\nUn Coordinador de intercambio se comunicar\u00e1 con usted en breve para revisar la transacci\u00f3n. Las tarifas de un intercambio aparecer\u00e1n en el HUD como parte de la venta. Los ingresos del cierre se entregar\u00e1n directamente a Affiliated 1031 para que se mantengan en su nombre y se desembolsen seg\u00fan sus instrucciones para la compra de su propiedad de reemplazo, sujeto a los t\u00e9rminos de su Contrato de intercambio. \u00a9 2022 Affiliated 1031, LLC. Todos los derechos reservados.<\/div><\/div><div id=\"wpforms-27245-field_56-container\" class=\"wpforms-field wpforms-field-hidden utm_campaign\" data-field-id=\"56\"><input type=\"hidden\" id=\"wpforms-27245-field_56\" name=\"wpforms[fields][56]\"><\/div><div id=\"wpforms-27245-field_57-container\" class=\"wpforms-field wpforms-field-hidden utm_source\" data-field-id=\"57\"><input type=\"hidden\" id=\"wpforms-27245-field_57\" name=\"wpforms[fields][57]\"><\/div><div id=\"wpforms-27245-field_58-container\" class=\"wpforms-field wpforms-field-hidden utm_medium\" data-field-id=\"58\"><input type=\"hidden\" id=\"wpforms-27245-field_58\" name=\"wpforms[fields][58]\"><\/div><div id=\"wpforms-27245-field_59-container\" class=\"wpforms-field wpforms-field-hidden utm_content\" data-field-id=\"59\"><input type=\"hidden\" id=\"wpforms-27245-field_59\" name=\"wpforms[fields][59]\"><\/div><div id=\"wpforms-27245-field_60-container\" class=\"wpforms-field wpforms-field-hidden utm_term\" data-field-id=\"60\"><input type=\"hidden\" id=\"wpforms-27245-field_60\" name=\"wpforms[fields][60]\"><\/div><div id=\"wpforms-27245-field_61-container\" class=\"wpforms-field wpforms-field-hidden handl_landing_page\" data-field-id=\"61\"><input type=\"hidden\" id=\"wpforms-27245-field_61\" name=\"wpforms[fields][61]\" value=\"https:\/\/www.affiliated1031.com\/es\/wp-json\/wp\/v2\/pages\/27242\"><\/div><div id=\"wpforms-27245-field_62-container\" class=\"wpforms-field wpforms-field-hidden handl_original_ref\" data-field-id=\"62\"><input type=\"hidden\" id=\"wpforms-27245-field_62\" name=\"wpforms[fields][62]\"><\/div><div id=\"wpforms-27245-field_63-container\" class=\"wpforms-field wpforms-field-hidden handl_url\" data-field-id=\"63\"><input type=\"hidden\" id=\"wpforms-27245-field_63\" name=\"wpforms[fields][63]\" value=\"https:\/\/www.affiliated1031.com\/es\/wp-json\/wp\/v2\/pages\/27242\"><\/div><div id=\"wpforms-27245-field_64-container\" class=\"wpforms-field wpforms-field-hidden handl_ref\" data-field-id=\"64\"><input type=\"hidden\" id=\"wpforms-27245-field_64\" name=\"wpforms[fields][64]\"><\/div><div id=\"wpforms-27245-field_65-container\" class=\"wpforms-field wpforms-field-hidden fbclid\" data-field-id=\"65\"><input type=\"hidden\" id=\"wpforms-27245-field_65\" name=\"wpforms[fields][65]\"><\/div><div id=\"wpforms-27245-field_66-container\" class=\"wpforms-field wpforms-field-hidden gclid\" data-field-id=\"66\"><input type=\"hidden\" id=\"wpforms-27245-field_66\" name=\"wpforms[fields][66]\"><\/div><div id=\"wpforms-27245-field_67-container\" class=\"wpforms-field wpforms-field-hidden traffic_source\" data-field-id=\"67\"><input type=\"hidden\" id=\"wpforms-27245-field_67\" name=\"wpforms[fields][67]\"><\/div><div id=\"wpforms-27245-field_72-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"72\"><input type=\"hidden\" id=\"wpforms-27245-field_72\" name=\"wpforms[fields][72]\"><\/div><div id=\"wpforms-27245-field_73-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"73\"><input type=\"hidden\" id=\"wpforms-27245-field_73\" name=\"wpforms[fields][73]\"><\/div><div id=\"wpforms-27245-field_69-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"69\"><input type=\"hidden\" id=\"wpforms-27245-field_69\" name=\"wpforms[fields][69]\"><\/div><div id=\"wpforms-27245-field_71-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"71\"><input type=\"hidden\" id=\"wpforms-27245-field_71\" name=\"wpforms[fields][71]\"><\/div><div id=\"wpforms-27245-field_70-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"70\"><input type=\"hidden\" id=\"wpforms-27245-field_70\" name=\"wpforms[fields][70]\"><\/div><div id=\"wpforms-27245-field_68-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"68\"><input type=\"hidden\" id=\"wpforms-27245-field_68\" name=\"wpforms[fields][68]\"><\/div><div id=\"wpforms-27245-field_74-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"74\"><input type=\"hidden\" id=\"wpforms-27245-field_74\" name=\"wpforms[fields][74]\"><\/div><div id=\"wpforms-27245-field_76-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"76\"><input type=\"hidden\" id=\"wpforms-27245-field_76\" name=\"wpforms[fields][76]\"><\/div><div id=\"wpforms-27245-field_75-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"75\"><input type=\"hidden\" id=\"wpforms-27245-field_75\" name=\"wpforms[fields][75]\"><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"27245\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-27245\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.affiliated1031.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container -->            <\/div>\n        <\/div>\n<\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image tatsu-bg-lazyload\" data-src = \"\"><\/div><\/div><div class=\"tatsu-overlay tatsu-column-overlay tatsu-animate-none\" ><\/div><\/div><style>.tatsu-row > .tatsu-rJnILdFT9.tatsu-column{width: 100%;}.tatsu-rJnILdFT9.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: normal;}.tatsu-rJnILdFT9 > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-rJnILdFT9 > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-rJnILdFT9 > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-rJnILdFT9 > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}@media only screen and (max-width:1377px) {.tatsu-row > .tatsu-rJnILdFT9.tatsu-column{width: 100%;}}@media only screen and (min-width:768px) and (max-width: 1024px) {.tatsu-row > .tatsu-rJnILdFT9.tatsu-column{width: 100%;}}@media only screen and (max-width: 767px) {.tatsu-row > .tatsu-rJnILdFT9.tatsu-column{width: 100%;}}<\/style><\/div><\/div><\/div><\/div><div class=\"tatsu-section-background-wrap\"><div class = \"tatsu-section-background tatsu-bg-lazyload\" data-src = \"\"><\/div><\/div><div class=\"tatsu-overlay tatsu-section-overlay\"><\/div><style>.tatsu-ByW3LUOKa5 .tatsu-section-pad{padding: 90px 0px 90px 0px;}.tatsu-ByW3LUOKa5 .tatsu-section-offset-wrap{transform: translateY(-0px);}.tatsu-ByW3LUOKa5 > .tatsu-bottom-divider{z-index: 9999;}.tatsu-ByW3LUOKa5 > .tatsu-top-divider{z-index: 9999;}.tatsu-ByW3LUOKa5 .tatsu-section-overlay{mix-blend-mode: normal;}@media only screen and (max-width: 767px) {.tatsu-ByW3LUOKa5 .tatsu-section-pad{padding: 40px 0px 60px 0px;}}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<div><a href=\"https:\/\/www.affiliated1031.com\/es\/hoja-de-trabajo-del-cliente\/\" class=\"exp-read-more exp-read-more-underlined\">Read More<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"class_list":["post-27242","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.affiliated1031.com\/es\/wp-json\/wp\/v2\/pages\/27242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.affiliated1031.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.affiliated1031.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.affiliated1031.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.affiliated1031.com\/es\/wp-json\/wp\/v2\/comments?post=27242"}],"version-history":[{"count":8,"href":"https:\/\/www.affiliated1031.com\/es\/wp-json\/wp\/v2\/pages\/27242\/revisions"}],"predecessor-version":[{"id":27934,"href":"https:\/\/www.affiliated1031.com\/es\/wp-json\/wp\/v2\/pages\/27242\/revisions\/27934"}],"wp:attachment":[{"href":"https:\/\/www.affiliated1031.com\/es\/wp-json\/wp\/v2\/media?parent=27242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}